{"id":998,"date":"2022-12-27T09:00:50","date_gmt":"2022-12-27T09:00:50","guid":{"rendered":"http:\/\/www.caetanoadvogados.adv.br\/site\/?p=998"},"modified":"2022-11-22T22:15:44","modified_gmt":"2022-11-22T22:15:44","slug":"contrato-de-seguro-e-condenacao-solidaria-da-seguradora","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/contrato-de-seguro-e-condenacao-solidaria-da-seguradora\/","title":{"rendered":"Contrato de Seguro e a condena\u00e7\u00e3o solid\u00e1ria da seguradora"},"content":{"rendered":"<p style=\"text-align: justify;\">Voc\u00ea sabia que, de acordo com a S\u00famula 537 do STJ, em a\u00e7\u00e3o de repara\u00e7\u00e3o de danos, a seguradora denunciada, se aceitar a denuncia\u00e7\u00e3o ou contestar o pedido do autor, pode ser\u00a0condenada, direta e solidariamente junto com o segurado, ao pagamento da indeniza\u00e7\u00e3o devida \u00e0 v\u00edtima, nos limites contratados na ap\u00f3lice? Em caso de d\u00favida consulte o Jur\u00eddico de sua confian\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que, de acordo com a S\u00famula 537 do STJ, em a\u00e7\u00e3o de repara\u00e7\u00e3o de danos, a seguradora denunciada, se aceitar a denuncia\u00e7\u00e3o ou contestar o pedido do autor, pode ser\u00a0condenada, direta e solidariamente junto com o segurado, ao pagamento da indeniza\u00e7\u00e3o devida \u00e0 v\u00edtima, nos limites contratados na ap\u00f3lice? Em caso de d\u00favida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/998"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=998"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/998\/revisions"}],"predecessor-version":[{"id":1000,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/998\/revisions\/1000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/999"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=998"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}