{"id":824,"date":"2022-01-25T09:00:00","date_gmt":"2022-01-25T09:00:00","guid":{"rendered":"http:\/\/caetanoadvogados.adv.br\/site\/?p=824"},"modified":"2022-01-06T22:06:36","modified_gmt":"2022-01-06T22:06:36","slug":"alteracao-valor-salario-minimo","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/alteracao-valor-salario-minimo\/","title":{"rendered":"Altera\u00e7\u00e3o do valor do Sal\u00e1rio M\u00ednimo"},"content":{"rendered":"<p style=\"text-align: justify;\">Com a MP 1.091\/2021, publicada no Di\u00e1rio Oficial da Uni\u00e3o em 31\/12\/2021, o sal\u00e1rio m\u00ednimo passa a ser de R$ 1.212,00 a partir do dia 1\u00ba\/01\/2022. Com o reajuste, o valor di\u00e1rio do sal\u00e1rio m\u00ednimo corresponder\u00e1 a R$40,40 e o valor hor\u00e1rio a R$5,51. O sal\u00e1rio m\u00ednimo de 2022 considera a corre\u00e7\u00e3o monet\u00e1ria pelo \u00cdndice Nacional de Pre\u00e7o ao Consumidor (INPC) e a proje\u00e7\u00e3o de infla\u00e7\u00e3o de dezembro de 2021, estimada pela \u00e1rea t\u00e9cnica do Minist\u00e9rio da Economia. No total, o aumento ser\u00e1 de 10,18%. Importante, lembrar, contudo que, atualmente, cinco estados brasileiros t\u00eam pisos regionais pr\u00f3prios: S\u00e3o Paulo, Rio de Janeiro, Paran\u00e1, Santa Catarina e Rio Grande do Sul. Por enquanto, apenas o Rio Grande do Sul j\u00e1 definiu o valor do m\u00ednimo, que ser\u00e1 observar\u00e1 faixas entre R$ 1.305,56 e R$ 1.654,50.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a MP 1.091\/2021, publicada no Di\u00e1rio Oficial da Uni\u00e3o em 31\/12\/2021, o sal\u00e1rio m\u00ednimo passa a ser de R$ 1.212,00 a partir do dia 1\u00ba\/01\/2022. Com o reajuste, o valor di\u00e1rio do sal\u00e1rio m\u00ednimo corresponder\u00e1 a R$40,40 e o valor hor\u00e1rio a R$5,51. O sal\u00e1rio m\u00ednimo de 2022 considera a corre\u00e7\u00e3o monet\u00e1ria pelo \u00cdndice [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/824"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=824"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/824\/revisions"}],"predecessor-version":[{"id":826,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/824\/revisions\/826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/825"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=824"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}