{"id":757,"date":"2021-10-12T09:00:39","date_gmt":"2021-10-12T09:00:39","guid":{"rendered":"http:\/\/caetanoadvogados.adv.br\/site\/?p=757"},"modified":"2021-09-08T12:12:14","modified_gmt":"2021-09-08T12:12:14","slug":"recebi-o-pagamento-mas-nao-cumpri-com-minha-obrigacao-e-agora","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/recebi-o-pagamento-mas-nao-cumpri-com-minha-obrigacao-e-agora\/","title":{"rendered":"Recebi o pagamento, mas n\u00e3o cumpri com minha obriga\u00e7\u00e3o. E agora?"},"content":{"rendered":"<p style=\"text-align: justify;\">Voc\u00ea sabia que o C\u00f3digo Civil prev\u00ea que todo aquele que recebeu o que lhe n\u00e3o era devido fica obrigado a restituir; obriga\u00e7\u00e3o que incumbe \u00e0quele que recebe d\u00edvida condicional antes de cumprida a condi\u00e7\u00e3o?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que o C\u00f3digo Civil prev\u00ea que todo aquele que recebeu o que lhe n\u00e3o era devido fica obrigado a restituir; obriga\u00e7\u00e3o que incumbe \u00e0quele que recebe d\u00edvida condicional antes de cumprida a condi\u00e7\u00e3o?<\/p>\n","protected":false},"author":2,"featured_media":758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/757"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"predecessor-version":[{"id":759,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/757\/revisions\/759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/758"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=757"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}