{"id":645,"date":"2021-06-02T01:49:06","date_gmt":"2021-06-02T01:49:06","guid":{"rendered":"http:\/\/www.caetanoadvogados.adv.br\/site\/?p=645"},"modified":"2021-06-02T01:49:06","modified_gmt":"2021-06-02T01:49:06","slug":"saude-nos-negocios-quando-foi-o-ultimo-check-de-sua-empresa","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/saude-nos-negocios-quando-foi-o-ultimo-check-de-sua-empresa\/","title":{"rendered":"SA\u00daDE NOS NEG\u00d3CIOS: QUANDO FOI O \u00daLTIMO CHECK-UP DE SUA EMPRESA?"},"content":{"rendered":"<p style=\"text-align: justify;\">Abrir uma empresa \u00e9 certamente um grande desafio para quem sonha ser empreendedor. No entanto, manter um neg\u00f3cio aberto tamb\u00e9m n\u00e3o \u00e9 tarefa f\u00e1cil. O mundo empresarial lida frequentemente com altos e baixos, e um empreendimento que esteve muito tempo no topo pode, de repente, se deparar com uma crise complexa, com risco de precisar at\u00e9 requerer uma recupera\u00e7\u00e3o judicial ou fechar. Mudan\u00e7as de contexto, de h\u00e1bitos de consumo, de inova\u00e7\u00e3o de processos e de tecnologias, s\u00e3o fatores para levar as empresas a situa\u00e7\u00f5es delicadas de continuidade. Kodak e Xerox, entre outras, s\u00e3o bons exemplos de empresas que n\u00e3o enxergaram que o seu ambiente de neg\u00f3cios estava em muta\u00e7\u00e3o. \u00c9 preciso entender a empresa como um ser vivo e org\u00e2nico, muito semelhante ao ser humano, tanto no que se refere a gest\u00e3o de seus h\u00e1bitos e pr\u00e1ticas saud\u00e1veis, como na preven\u00e7\u00e3o e cuidados que devem ser tomados para quem quer ter uma vida longa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abrir uma empresa \u00e9 certamente um grande desafio para quem sonha ser empreendedor. No entanto, manter um neg\u00f3cio aberto tamb\u00e9m n\u00e3o \u00e9 tarefa f\u00e1cil. O mundo empresarial lida frequentemente com altos e baixos, e um empreendimento que esteve muito tempo no topo pode, de repente, se deparar com uma crise complexa, com risco de precisar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/645"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=645"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/645\/revisions"}],"predecessor-version":[{"id":648,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/645\/revisions\/648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/647"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=645"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}