{"id":641,"date":"2021-06-08T09:00:49","date_gmt":"2021-06-08T09:00:49","guid":{"rendered":"http:\/\/caetanoadvogados.adv.br\/site\/?p=641"},"modified":"2021-06-02T01:48:04","modified_gmt":"2021-06-02T01:48:04","slug":"como-saber-se-seus-dados-foram-usados-para-abrir-conta-ou-pedir-emprestimos","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/como-saber-se-seus-dados-foram-usados-para-abrir-conta-ou-pedir-emprestimos\/","title":{"rendered":"COMO SABER SE SEUS DADOS FORAM USADOS PARA ABRIR CONTA OU PEDIR EMPR\u00c9STIMOS?"},"content":{"rendered":"<p>Muitos brasileiros est\u00e3o descobrindo que os seus nomes e dados foram utilizados para realizar a abertura de contas correntes e tomar empr\u00e9stimos ilegais. Ao todo, 223 milh\u00f5es de n\u00fameros de CPF foram expostos. O site Registrato, do Banco Central, permite monitorar quais contas correntes e quantos empr\u00e9stimos est\u00e3o vinculados ao seu CPF. \u00c9 poss\u00edvel fazer o cadastro pelo aplicativo do banco no celular e pela internet. Basta um credenciamento simples para voc\u00ea controlar a sua situa\u00e7\u00e3o em todas as institui\u00e7\u00f5es financeiras. Caso voc\u00ea verifique que h\u00e1 contas ou empr\u00e9stimos e em seu nome que voc\u00ea n\u00e3o identifica, entre em contato com a institui\u00e7\u00e3o financeira ou com o Banco Central.<br \/>\n.<br \/>\n&#x1f447; <strong>Veja abaixo como fazer o credenciamento pelo celular e pela internet.<\/strong><br \/>\n.<br \/>\n&#x1f449; <strong>Como come\u00e7ar<\/strong><br \/>\n.<br \/>\nAcesse o site do Banco Central que permite consultar quantas contas banc\u00e1rias e empr\u00e9stimos voc\u00ea possui. Se for o seu primeiro acesso, clique em pessoa f\u00edsica e comece a fazer o credenciamento. H\u00e1 v\u00e1rias op\u00e7\u00f5es para fazer o credenciamento: celular, internet banking e cadastro digital. \u00c9 poss\u00edvel fazer o credenciamento tamb\u00e9m de forma presencial e pelo correio, mas essas modalidades est\u00e3o suspensas por causa da pandemia.<br \/>\n.<br \/>\n&#x1f449; <strong>Credenciamento pelo celular<\/strong><br \/>\n.<br \/>\nDepois de indicar o primeiro acesso, \u00e9 preciso abrir o aplicativo do seu banco no celular e seguir as instru\u00e7\u00f5es do Banco Central. O cadastro realizado por meio do aplicativo vai resultar num PIN. Guarde este n\u00famero, porque ele ser\u00e1 necess\u00e1rio na pr\u00f3xima etapa. O Banco Central detalha o caminho de cadastro para ser feito no aplicativo do seu banco. O credenciamento pelo celular precisa ser conclu\u00eddo no site do Banco Central. Prossiga com o cadastro e preencha todas as informa\u00e7\u00f5es. Lembre-se de incluir o n\u00famero do PIN criado pelo aplicativo do seu banco. E n\u00e3o se esque\u00e7a: a institui\u00e7\u00e3o financeira informada tem de ser a mesma em todo o cadastro. Com o fim do cadastro, j\u00e1 \u00e9 poss\u00edvel acessar a p\u00e1gina Registrato. Se voc\u00ea n\u00e3o for transferido automaticamente, Fa\u00e7a o login e utilize senha cadastrada. Se ela n\u00e3o funcionar, tente criar uma nova senha. Na pr\u00f3xima etapa, j\u00e1 logado, clique em \u201cMeus Endividamentos\u201d e \u201cMeus Relacionamentos Financeiros\u201d e crie os relat\u00f3rios. Pronto. Voc\u00ea saber\u00e1 se existem empr\u00e9stimos e contas abertas em seu nome em todas as institui\u00e7\u00f5es.<br \/>\n.<br \/>\n&#x1f449; <strong>Credenciamento pela internet<\/strong><br \/>\n.<br \/>\nAo selecionar o Internet banking, comece pela frase de seguran\u00e7a na p\u00e1gina do Banco Central. Preencha todos os seus dados para conseguir a frase de seguran\u00e7a. Com a frase de seguran\u00e7a criada, \u00e9 poss\u00edvel fazer o credenciamento no site do seu banco. A frase vale por 48 horas. Siga as instru\u00e7\u00f5es da p\u00e1gina do Banco Central.V\u00e1 para o site do seu banco. Se houver uma \u00e1rea de busca, pesquisar por Registrado pode ser um caminho mais r\u00e1pido para voc\u00ea conseguir fazer o cadastro da chave. Com a frase cadastrada no seu banco, siga para a pr\u00f3xima etapa. Preencha todos os campos. Lembre-se que voc\u00ea vai utilizar novamente a sua frase. A institui\u00e7\u00e3o financeira informada tem de ser a mesma em todo o cadastro. Com o fim do cadastro, j\u00e1 \u00e9 poss\u00edvel acessar a p\u00e1gina do Registrato. Se voc\u00ea n\u00e3o for transferido automaticamente, Fa\u00e7a o login e utiliza senha cadastrada. Se ela n\u00e3o funcionar, tente criar uma nova senha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muitos brasileiros est\u00e3o descobrindo que os seus nomes e dados foram utilizados para realizar a abertura de contas correntes e tomar empr\u00e9stimos ilegais. Ao todo, 223 milh\u00f5es de n\u00fameros de CPF foram expostos. O site Registrato, do Banco Central, permite monitorar quais contas correntes e quantos empr\u00e9stimos est\u00e3o vinculados ao seu CPF. \u00c9 poss\u00edvel fazer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/641"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=641"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/641\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/641\/revisions\/643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/642"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=641"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}