{"id":525,"date":"2021-02-04T14:16:00","date_gmt":"2021-02-04T14:16:00","guid":{"rendered":"http:\/\/caetanoadvogados.adv.br\/site\/?p=525"},"modified":"2021-02-04T14:16:00","modified_gmt":"2021-02-04T14:16:00","slug":"estatistica-de-reclamacoes-trabalhistas-no-rs-em-2020","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/estatistica-de-reclamacoes-trabalhistas-no-rs-em-2020\/","title":{"rendered":"ESTAT\u00cdSTICA DE RECLAMA\u00c7\u00d5ES TRABALHISTAS NO RS EM 2020"},"content":{"rendered":"<p style=\"text-align: justify;\">Em 2020, a Justi\u00e7a do Trabalho ga\u00facha recebeu, no primeiro grau, 112.391 novos processos. O pedido mais frequente nos processos ajuizados em 2020 foi a multa dos 40% do FGTS, que deve ser paga em rescis\u00f5es sem justa causa. Entre os 10 pedidos que mais aparecem nas a\u00e7\u00f5es, sete s\u00e3o verbas rescis\u00f3rias (aviso pr\u00e9vio, d\u00e9cimo terceiro e f\u00e9rias proporcionais, entre outras). Completam a lista: adicional de insalubridade (4\u00ba lugar), dep\u00f3sitos e diferen\u00e7as de recolhimento de FGTS (9\u00ba lugar) e indeniza\u00e7\u00e3o por danos morais (10\u00ba lugar).<\/p>\n<p style=\"text-align: justify;\">Do total de processos solucionados no primeiro grau em 2020, 44% foram resolvidos por meio de acordo entre as partes, 35% tiveram proced\u00eancia parcial (autor ganhou um ou mais pedidos, mas outros n\u00e3o), 12% foram julgados improcedentes (nenhum pedido do autor foi atendido) e 9% foram totalmente procedentes (todos os pedidos atendidos).<\/p>\n<p style=\"text-align: justify;\">Em 2020, o tempo m\u00e9dio para o julgamento de um processo trabalhista no Rio Grande do Sul foi de 261 dias no primeiro grau e de 199 dias na segunda inst\u00e2ncia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Fonte<\/strong>: https:\/\/www.trt4.jus.br\/portais\/trt4\/modulos\/noticias\/439988<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2020, a Justi\u00e7a do Trabalho ga\u00facha recebeu, no primeiro grau, 112.391 novos processos. O pedido mais frequente nos processos ajuizados em 2020 foi a multa dos 40% do FGTS, que deve ser paga em rescis\u00f5es sem justa causa. Entre os 10 pedidos que mais aparecem nas a\u00e7\u00f5es, sete s\u00e3o verbas rescis\u00f3rias (aviso pr\u00e9vio, d\u00e9cimo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/525"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=525"}],"version-history":[{"count":1,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/525\/revisions"}],"predecessor-version":[{"id":527,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/525\/revisions\/527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/526"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=525"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}