{"id":502,"date":"2021-01-13T19:41:12","date_gmt":"2021-01-13T19:41:12","guid":{"rendered":"http:\/\/caetanoadvogados.adv.br\/site\/?p=502"},"modified":"2021-01-13T19:43:12","modified_gmt":"2021-01-13T19:43:12","slug":"guarda-de-documentos-fiscais-prazos","status":"publish","type":"post","link":"https:\/\/www.caetanoadvogados.adv.br\/site\/guarda-de-documentos-fiscais-prazos\/","title":{"rendered":"GUARDA DE DOCUMENTOS FISCAIS &#8211; PRAZOS"},"content":{"rendered":"<p><strong>Por Marco Antonio Espada<\/strong><\/p>\n<p><strong>IN\u00cdCIO DE ANO &#8211; ARQUIVAR OU DESFAZER<\/strong><br \/>\nNo in\u00edcio de cada do ano lembramos que se trata da \u00e9poca de fechar o balan\u00e7o anual e de arquivar ou desfazer dos documentos ou papeis do ano anterior, que ter\u00e3o ou n\u00e3o serventia.<\/p>\n<p>Mas quais documentos fiscais devemos guardar? Qual o prazo estipulado na legisla\u00e7\u00e3o?<\/p>\n<p>Quais as normas que determinam a sua apresenta\u00e7\u00e3o, seja para fins fiscais ou estejam em processo judicial?<\/p>\n<p><strong>E quanto a LGPD?<\/strong><br \/>\n<strong>MAS AFINAL, QUAL O PRAZO PARA ARQUIVAR OS DOCUMENTOS FISCAIS ?<\/strong><br \/>\nA legisla\u00e7\u00e3o determina que os documentos fiscais devem permanecer arquivados por cinco anos. Desta forma, cumpre-se o per\u00edodo de guarda dos documentos relacionados com os tributos no prazo de decad\u00eancia e prescri\u00e7\u00e3o, previstos nos artigos 173 e 174 do C\u00f3digo Tribut\u00e1rio Nacional (CTN).<br \/>\nArt. 173. O direito de a Fazenda P\u00fablica constituir o cr\u00e9dito tribut\u00e1rio extingue-se ap\u00f3s 5 (cinco) anos, contados:<br \/>\nI &#8211; em primeiro lugar, aos d\u00e9bitos por obriga\u00e7\u00e3o pr\u00f3pria, e em segundo lugar aos decorrentes de responsabilidade tribut\u00e1ria;<br \/>\nII &#8211; primeiramente, \u00e0s contribui\u00e7\u00f5es de melhoria, depois \u00e0s taxas e por fim aos impostos;<br \/>\nIII &#8211; na ordem crescente dos prazos de prescri\u00e7\u00e3o;<br \/>\nIV &#8211; na ordem decrescente dos montantes.<br \/>\nArt.174. A a\u00e7\u00e3o para a cobran\u00e7a do cr\u00e9dito tribut\u00e1rio prescreve em cinco anos, contados da data da sua constitui\u00e7\u00e3o definitiva. III &#8211; de exig\u00eancia, por mais de uma pessoa jur\u00eddica de direito p\u00fablico, de tributo id\u00eantico sobre um mesmo fato gerador.<br \/>\nPrescri\u00e7\u00e3o \u00e9 o decurso do prazo de cinco anos para cobrar judicialmente o tributo devido. No fim desse prazo, o cr\u00e9dito tribut\u00e1rio ser\u00e1 extinto (art. 156, v, do CTN) e n\u00e3o mais poder\u00e1 ser exigido pelo Fisco.<\/p>\n<p>Decad\u00eancia \u00e9 o decurso do prazo de cinco anos que o Fisco tem para constituir o cr\u00e9dito tribut\u00e1rio, por meio da notifica\u00e7\u00e3o de lan\u00e7amento ou do auto de infra\u00e7\u00e3o.<\/p>\n<p><strong><br \/>\nLIVROS OBRIGAT\u00d3RIOS E DEMAIS COMPROVANTES<\/strong><br \/>\nDevemos considerar que esse prazo decadencial e prescricional se aplica aos livros obrigat\u00f3rios e comprovantes de lan\u00e7amentos.<\/p>\n<p>Em conformidade com o artigo 195, par\u00e1grafo \u00fanico do CTN est\u00e1 previsto:<br \/>\nArt.195. Para os efeitos da legisla\u00e7\u00e3o tribut\u00e1ria, n\u00e3o t\u00eam aplica\u00e7\u00e3o quaisquer disposi\u00e7\u00f5es legais excludentes ou limitativas do direito de examinar mercadorias, livros, arquivos, documentos, pap\u00e9is e efeitos comerciais ou fiscais, dos comerciantes industriais ou produtores, ou da obriga\u00e7\u00e3o destes de exibi-los.<br \/>\nDocumentos trabalhistas e contribui\u00e7\u00f5es previdenci\u00e1rias<br \/>\nOs prazos gerais dos documentos e arquivos trabalhistas podem variar de 2 a 30 anos, n\u00e3o h\u00e1 uma regra espec\u00edfica, devendo o empregador adotar um crit\u00e9rio mais conservador poss\u00edvel entretanto citamos como exemplo na CF a seguinte disposi\u00e7\u00e3o:<br \/>\nConstitui\u00e7\u00e3o Federal\/88, Art. 7\u00ba&#8230; XXIX &#8211; a\u00e7\u00e3o, quanto aos cr\u00e9ditos resultantes das rela\u00e7\u00f5es de trabalho, com prazo prescricional de cinco anos para os trabalhadores urbanos e rurais, at\u00e9 o limite de dois anos ap\u00f3s a extin\u00e7\u00e3o do contrato de trabalho;(Reda\u00e7\u00e3o Emenda Constitucional n\u00ba 28 de 25\/5\/00).<br \/>\nQuanto aos documentos previdenci\u00e1rios, prev\u00ea o par\u00e1grafo 1\u00ba. Do artigo 83 do Decreto 3.048\/99, a obrigatoriedade de a empresa manter \u00e0 disposi\u00e7\u00e3o da fiscaliza\u00e7\u00e3o, durante dez anos, os documentos comprobat\u00f3rios do cumprimento de suas obriga\u00e7\u00f5es legais, inclusive os arquivos digitais do sistema de processamento eletr\u00f4nico de dados trabalhistas e previdenci\u00e1rios.<br \/>\nArt. 83<br \/>\n[&#8230;]\n\u00a71\u00ba A empresa e o empregador dom\u00e9stico dever\u00e3o conservar, durante o prazo decadencial de que trata o art. 348, os comprovantes dos pagamentos e as c\u00f3pias das certid\u00f5es correspondentes, para exame pela fiscaliza\u00e7\u00e3o.&#8221;<br \/>\nLGPD &#8211; Algumas considera\u00e7\u00f5es<br \/>\nA LGPD tem uma legisla\u00e7\u00e3o espec\u00edfica sobre pol\u00edticas de armazenamento de dados que variam de acordo com as necessidades de cada ramo de atividade empresarial. Logo, podem haver limites mais r\u00edgidos para a extens\u00e3o de dados, bem como o per\u00edodo que eles podem ser armazenados antes de serem apagados. Por isso \u00e9 fundamental avaliar se os dados trazem interfer\u00eancia nos resultados econ\u00f4micos-fiscais da empresa em se tratando de arquivos de documentos tribut\u00e1rios.<\/p>\n<p><strong><br \/>\nExemplos de documentos relacionados com os impostos e prazo de guarda:<\/strong><\/p>\n<p>Tribut\u00e1rio<br \/>\n* 5 ANOS<\/p>\n<p>IMPOSTO DE RENDA (Art.173\/174 do CTN)<br \/>\nCSLL\/PIS\/COFINS(Art.173\/174 do CTN)<br \/>\nNOTAS FISCAIS, RECIBOS E DEMAIS COMPROVANTES(Art.173\/174 do CTN)<br \/>\nLIVROS FISCAIS E CONT\u00c1BEIS (Art.195\/174 do CTN)<br \/>\nSIMPLES NACIONAL (Art. 26, II, LC 123\/2006 e Arts. 195 e 174, CTN)<br \/>\nSISTEMA ELETRONICO DE DADOS E ESCRITURA\u00c7\u00c3O FISCAL OU CONTABIL(Art. 11, Lei N\u00ba 8.218\/1991 e Art. 173, CTN)<\/p>\n<p>Trabalhista\/Previdenci\u00e0rio<br \/>\n* 30 anos<br \/>\nFGTS (Art. 23, \u00a7 5\u00ba, lei n.\u00ba 8.036\/1990<\/p>\n<p>GFIP &#8211; GUIA RECOLHIMENTO DO FGTS E INFORMA\u00c7\u00d5ES \u00c0 PREVID\u00caNCIA SOCIAL(Art. 23, \u00a7 5\u00ba, lei n.\u00ba 8.036\/1990)<\/p>\n<p>GRFC &#8211; GUIA DE RECOLHIMENTO RESCIS\u00d3RIO DO FGTS E DA CONTRIBUI\u00c7\u00c3O SOCIAL(Art. 23, \u00a7 5\u00ba, lei n.\u00ba 8.036\/1990)<\/p>\n<p>* 10 ANOS<br \/>\nCONTRIBUI\u00c7\u00c3O PREVIDENCI\u00c1RIA &#8211; GPS(Arts. 173 e 174, CTN e arts. 103 e 103-A da lei n.\u00ba 8.213\/1991)<\/p>\n<p>FOLHA DE PAGAMENTO(Art. 225, I e \u00a7 5\u00ba, decreto n.\u00ba 3.048\/1999)<\/p>\n<p>SISTEMAS ELETR\u00d4NICOS DE DADOS TRABALHISTAS E PREVIDENCI\u00c1RIOS(Art. 225, \u00a7 22, decreto n.\u00ba 3.048\/1999)<\/p>\n<p>* 5 ANOS<br \/>\nCONTRIBUI\u00c7\u00c3O SINDICAL &#8211; GRCSU(Arts. 173 e 217, I, CTN)<\/p>\n<p>CAGED &#8211; CADASTRO GERAL DE EMPREGADOS E DESEMPREGADOS(Art. 2\u00ba, \u00a7 1\u00ba, Portaria TEM n.\u00ba 1.129\/2014)<\/p>\n<p>RAIS &#8211; RELA\u00c7\u00c3O ANUAL DE INFORMA\u00c7\u00d5ES SOCIAIS.(Art. 8\u00ba, Portaria MTB n.\u00ba 1.464\/2016)<\/p>\n<p>RECIBO DE PAGAMENTO DE SAL\u00c1RIO, F\u00c9RIAS, 13\u00ba SAL\u00c1RIO E CONTROLE DE PONTO (Art. 7\u00ba, XXIX, CF e art. 11 CLT)<\/p>\n<p>* 2 ANOS<br \/>\nTERMO DE RESCIS\u00c3O DO CONTRATO DE TRABALHO, PEDIDO DE DEMISS\u00c3O E AVISO PR\u00c9VIO(Art. 7\u00ba, XXIX, CF e art. 11 CLT)<\/p>\n<p>INDETERMINADO<br \/>\nCONTRATO DE TRABALHO<\/p>\n<p>LIVRO OU FICHA DE REGISTRO DE EMPREGADO<\/p>\n<p><strong><br \/>\nFonte: Fecom\u00e9rcio\/SP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Marco Antonio Espada IN\u00cdCIO DE ANO &#8211; ARQUIVAR OU DESFAZER No in\u00edcio de cada do ano lembramos que se trata da \u00e9poca de fechar o balan\u00e7o anual e de arquivar ou desfazer dos documentos ou papeis do ano anterior, que ter\u00e3o ou n\u00e3o serventia. Mas quais documentos fiscais devemos guardar? Qual o prazo estipulado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/502"}],"collection":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":3,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"predecessor-version":[{"id":506,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/posts\/502\/revisions\/506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media\/503"}],"wp:attachment":[{"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/tags?post=502"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.caetanoadvogados.adv.br\/site\/wp-json\/wp\/v2\/yst_prominent_words?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}